{"id":6909,"date":"2026-07-15T02:38:18","date_gmt":"2026-07-15T05:38:18","guid":{"rendered":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/"},"modified":"2026-07-15T02:38:19","modified_gmt":"2026-07-15T05:38:19","slug":"shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin","status":"publish","type":"post","link":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/","title":{"rendered":"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de &#8216;Ruin&#8217;"},"content":{"rendered":"<p>Shawn Mendes ha lanzado \u201cRuin \u200b\u200b(Live From Boston)\u201d, una interpretaci\u00f3n in\u00e9dita del tema de 2016, que este a\u00f1o cumple diez a\u00f1os. Un paquete de dos canciones que combina la versi\u00f3n original de estudio con la grabaci\u00f3n en vivo ya est\u00e1 disponible en todas las plataformas de transmisi\u00f3n, junto con un video oficial de la presentaci\u00f3n en el canal de YouTube de Mendes.<\/p>\n<p>\u201cRuin\u201d apareci\u00f3 por primera vez en el segundo \u00e1lbum de Mendes de 2016, <em>Iluminar<\/em>convirti\u00e9ndose r\u00e1pidamente en un favorito entre los fan\u00e1ticos y un elemento b\u00e1sico de sus shows en vivo. El lanzamiento sigue al d\u00e9cimo aniversario del mes pasado de \u201cTreat You Better\u201d, parte de la celebraci\u00f3n anual de Mendes de su segundo \u00e1lbum de estudio y hogar de algunos de sus \u00e9xitos m\u00e1s duraderos.<\/p>\n<div align=\"center\">\n<div class=\"udiscover-store-container\">\n<div id='udiscover-store-two-product'><\/div>\n<\/div>\n<p>\/*<!(CDATA(*\/(function (){var scriptURL='https:\/\/sdks.shopifycdn.com\/buy-button\/latest\/buy-button-storefront.min.js';if(window.ShopifyBuy){if(window.ShopifyBuy.UI){ShopifyBuyInit();}else{loadScript();}}else{loadScript();}funci\u00f3n loadScript(){var script=document.createElement('script');script.async=true;script.src=scriptURL;(document.getElementsByTagName('head')(0)|| document.getElementsByTagName('body')(0)).appendChild(script);script.onload=ShopifyBuyInit;} function ShopifyBuyInit(){var cliente=ShopifyBuy.buildClient({dominio:'udiscover.myshopify.com',storefrontAccessToken: 'bdc89f347d2ce61c1feeb9f8c60b2b98',}); ShopifyBuy.UI.onReady(cliente).luego(funci\u00f3n(ui){ ui.createComponent('productSet',{ id:(7454007197773,6685667229773), nodo:document.getElementById('udiscover-store-two-product'), moneyFormat:'%24%7B%7Bamount%7D%7D', opciones:{&quot;producto&quot;:{&quot;marco flotante&quot;:FALSO,&quot;eventos&quot;:{antes deInit:funci\u00f3n(producto){Objeto.defineProperty(producto,&quot;es bot\u00f3n&quot;,{get:function(){return true;}});Object.defineProperty(producto,&quot;opciones&quot;{get:function(){return this.config(this.typeKey);}});var actualOnButtonClick=product.onButtonClick;product.onButtonClick=function(event,target) {event.stopImmediatePropagation();this.options.buttonDestination=&quot;modal&quot;;actualOnButtonClick.call(este,evento,destino);};}},\n&quot;bot\u00f3nDestino&quot;:&quot;modal&quot;,&quot;contenido&quot;:{&quot;opciones&quot;:verdadero},&quot;texto&quot;:{&quot;bot\u00f3n&quot;:&quot;Ordene ahora&quot;,&quot;Agotado&quot;:&quot;Lo sentimos, esto est\u00e1 agotado.&quot;}},&quot;conjunto de productos&quot;:{&quot;marco flotante&quot;:FALSO},&quot;modalProducto&quot;:{&quot;marco flotante&quot;:FALSO,&quot;contenido&quot;:{&quot;imagen&quot;:FALSO,&quot;imgConCarrusel&quot;:verdadero,&quot;bot\u00f3n&quot;:FALSO,&quot;bot\u00f3nConCantidad&quot;:verdadero}},&quot;modal&quot;:{&quot;marco flotante&quot;:FALSO},&quot;opci\u00f3n&quot;:{&quot;marco flotante&quot;:FALSO},&quot;carro&quot;:{&quot;marco flotante&quot;:FALSO},&quot;palanca&quot;:{&quot;marco flotante&quot;:FALSO,&quot;contenido&quot;:{&quot;icono&quot;:FALSO}},&quot;art\u00edculo de l\u00ednea&quot;:{&quot;marco flotante&quot;:FALSO}},}); }); } })(); \/*))>*\/ <\/div>\n<\/p>\n<p>Cuando fue lanzado, <em>Iluminar<\/em> debut\u00f3 en el puesto n\u00famero 1 del Billboard 200; desde entonces obtuvo doble platino, consolidando su estatus como uno de los discos pop m\u00e1s importantes de 2016. Otros aspectos destacados de la lista de canciones incluyen \u201cMercy\u201d y \u201cThere&#8217;s Nothing Holding Me Back\u201d, los cuales precedieron al lanzamiento del \u00e1lbum como sencillos y permanecen entre sus canciones m\u00e1s populares en la actualidad.<\/p>\n<p>Junto con el lanzamiento de \u201cRuin \u200b\u200b(Live In Boston)\u201d, Mendes present\u00f3 dos nuevos modelos de guitarra exclusivos con Martin: la edici\u00f3n limitada 000-28 Shawn Mendes y la 000-10E Shawn Mendes, ambas inspiradas en una Martin vintage de los a\u00f1os 20 en la que la estrella canadiense suele escribir y grabar. &#8220;Estos dos modelos son hermosos y atemporales&#8221;, dijo Mendes, y agreg\u00f3 que espera que inspiren a otros cantautores &#8220;como el de Martin, que me ha inspirado a m\u00ed durante a\u00f1os&#8221;. Una parte de las ventas de cada guitarra se destinar\u00e1 a apoyar a la Fundaci\u00f3n Shawn Mendes.<\/p>\n<div class=\"uD-YT-container\"><img decoding=\"async\" src=\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/1784093898_794_Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg\" alt=\"V\u00eddeo de YouTube\"><br \/>Haga clic para cargar v\u00eddeo<\/div>\n<p><em>Iluminar<\/em>Las tierras del aniversario de esta\u00f1o llegan en un periodo de hitos para el cantante. En abril pasado, su sencillo \u201cIn My Blood\u201d, nominado al Grammy de 2018, super\u00f3 mil millones de reproducciones en Spotify. El logro se produjo tras el lanzamiento de su \u00e1lbum m\u00e1s reciente, el hom\u00f3nimo. <em>Shawn<\/em>que cay\u00f3 en 2024 a trav\u00e9s de Island Records. Fue escrito en gran parte con su propia guitarra Martin antigua, la misma que inspir\u00f3 su \u00faltima asociaci\u00f3n con la marca.<\/p>\n<p><b>Escuche \u201cRuin \u200b\u200b(Live From Boston)\u201d de Shawn Mendes aqu\u00ed.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shawn Mendes ha lanzado \u201cRuin \u200b\u200b(Live From Boston)\u201d, una interpretaci\u00f3n in\u00e9dita del tema de 2016, que este a\u00f1o cumple diez a\u00f1os. Un paquete de dos<\/p>\n","protected":false},"author":1,"featured_media":6910,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[463,201,4780,590,2110,3807,4201,191,977,59],"class_list":["post-6909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-ultimo","tag-antes","tag-comparte","tag-escuchada","tag-mendes","tag-nunca","tag-ruin","tag-shawn","tag-una","tag-version","tag-vivo","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de &#039;Ruin&#039;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de &#039;Ruin&#039;\" \/>\n<meta property=\"og:description\" content=\"Shawn Mendes ha lanzado \u201cRuin \u200b\u200b(Live From Boston)\u201d, una interpretaci\u00f3n in\u00e9dita del tema de 2016, que este a\u00f1o cumple diez a\u00f1os. Un paquete de dos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/\" \/>\n<meta property=\"og:site_name\" content=\"Conservatorio de M\u00fasica Juli\u00e1n Aguirre\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T05:38:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T05:38:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"820\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Javier Figueroa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Figueroa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/\"},\"author\":{\"name\":\"Javier Figueroa\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/person\/6558b0cfedee7ddc5425602b237d5722\"},\"headline\":\"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de &#8216;Ruin&#8217;\",\"datePublished\":\"2026-07-15T05:38:18+00:00\",\"dateModified\":\"2026-07-15T05:38:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/\"},\"wordCount\":418,\"publisher\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg\",\"keywords\":[\"antes\",\"comparte\",\"escuchada\",\"Mendes\",\"nunca\",\"Ruin\",\"Shawn\",\"una\",\"versi\u00f3n\",\"vivo\"],\"articleSection\":[\"El \u00faltimo\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/\",\"url\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/\",\"name\":\"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de 'Ruin'\",\"isPartOf\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg\",\"datePublished\":\"2026-07-15T05:38:18+00:00\",\"dateModified\":\"2026-07-15T05:38:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#primaryimage\",\"url\":\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg\",\"contentUrl\":\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg\",\"width\":820,\"height\":820,\"caption\":\"Shawn Mendes Ruin Live From Boston\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/web.consaguirre.com.ar\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de &#8216;Ruin&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#website\",\"url\":\"https:\/\/web.consaguirre.com.ar\/noticias\/\",\"name\":\"Conservatorio de M\u00fasica Juli\u00e1n Aguirre\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/web.consaguirre.com.ar\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#organization\",\"name\":\"Conservatorio de M\u00fasica Juli\u00e1n Aguirre\",\"url\":\"https:\/\/web.consaguirre.com.ar\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2024\/08\/Banner-Aguirre-23.jpg\",\"contentUrl\":\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2024\/08\/Banner-Aguirre-23.jpg\",\"width\":1192,\"height\":600,\"caption\":\"Conservatorio de M\u00fasica Juli\u00e1n Aguirre\"},\"image\":{\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/person\/6558b0cfedee7ddc5425602b237d5722\",\"name\":\"Javier Figueroa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2024\/08\/Consaguirre-scaled.jpg\",\"contentUrl\":\"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2024\/08\/Consaguirre-scaled.jpg\",\"caption\":\"Javier Figueroa\"},\"description\":\"Me llamo Javier Figueroa y soy redactor para el sitio oficial del Conservatorio de M\u00fasica Juli\u00e1n Aguirre en Buenos Aires, consaguirre.com. Apasionado por la m\u00fasica y la escritura, me esfuerzo por destacar los talentos y eventos de nuestra prestigiosa instituci\u00f3n. Mi trayectoria se nutre de una profunda admiraci\u00f3n por los artistas, haciendo de cada art\u00edculo una celebraci\u00f3n de la creatividad y la cultura musical.\",\"sameAs\":[\"https:\/\/web.consaguirre.com.ar\/noticias\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de 'Ruin'","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/","og_locale":"es_ES","og_type":"article","og_title":"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de 'Ruin'","og_description":"Shawn Mendes ha lanzado \u201cRuin \u200b\u200b(Live From Boston)\u201d, una interpretaci\u00f3n in\u00e9dita del tema de 2016, que este a\u00f1o cumple diez a\u00f1os. Un paquete de dos","og_url":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/","og_site_name":"Conservatorio de M\u00fasica Juli\u00e1n Aguirre","article_published_time":"2026-07-15T05:38:18+00:00","article_modified_time":"2026-07-15T05:38:19+00:00","og_image":[{"width":820,"height":820,"url":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg","type":"image\/jpeg"}],"author":"Javier Figueroa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Javier Figueroa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#article","isPartOf":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/"},"author":{"name":"Javier Figueroa","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/person\/6558b0cfedee7ddc5425602b237d5722"},"headline":"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de &#8216;Ruin&#8217;","datePublished":"2026-07-15T05:38:18+00:00","dateModified":"2026-07-15T05:38:19+00:00","mainEntityOfPage":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/"},"wordCount":418,"publisher":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#organization"},"image":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#primaryimage"},"thumbnailUrl":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg","keywords":["antes","comparte","escuchada","Mendes","nunca","Ruin","Shawn","una","versi\u00f3n","vivo"],"articleSection":["El \u00faltimo"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/","url":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/","name":"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de 'Ruin'","isPartOf":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#primaryimage"},"image":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#primaryimage"},"thumbnailUrl":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg","datePublished":"2026-07-15T05:38:18+00:00","dateModified":"2026-07-15T05:38:19+00:00","breadcrumb":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#primaryimage","url":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg","contentUrl":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/Shawn-Mendes-comparte-una-version-en-vivo-nunca-antes-escuchada.jpg","width":820,"height":820,"caption":"Shawn Mendes Ruin Live From Boston"},{"@type":"BreadcrumbList","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/shawn-mendes-comparte-una-version-en-vivo-nunca-antes-escuchada-de-ruin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/web.consaguirre.com.ar\/noticias\/"},{"@type":"ListItem","position":2,"name":"Shawn Mendes comparte una versi\u00f3n en vivo nunca antes escuchada de &#8216;Ruin&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#website","url":"https:\/\/web.consaguirre.com.ar\/noticias\/","name":"Conservatorio de M\u00fasica Juli\u00e1n Aguirre","description":"","publisher":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.consaguirre.com.ar\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#organization","name":"Conservatorio de M\u00fasica Juli\u00e1n Aguirre","url":"https:\/\/web.consaguirre.com.ar\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2024\/08\/Banner-Aguirre-23.jpg","contentUrl":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2024\/08\/Banner-Aguirre-23.jpg","width":1192,"height":600,"caption":"Conservatorio de M\u00fasica Juli\u00e1n Aguirre"},"image":{"@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/person\/6558b0cfedee7ddc5425602b237d5722","name":"Javier Figueroa","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/web.consaguirre.com.ar\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2024\/08\/Consaguirre-scaled.jpg","contentUrl":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-content\/uploads\/2024\/08\/Consaguirre-scaled.jpg","caption":"Javier Figueroa"},"description":"Me llamo Javier Figueroa y soy redactor para el sitio oficial del Conservatorio de M\u00fasica Juli\u00e1n Aguirre en Buenos Aires, consaguirre.com. Apasionado por la m\u00fasica y la escritura, me esfuerzo por destacar los talentos y eventos de nuestra prestigiosa instituci\u00f3n. Mi trayectoria se nutre de una profunda admiraci\u00f3n por los artistas, haciendo de cada art\u00edculo una celebraci\u00f3n de la creatividad y la cultura musical.","sameAs":["https:\/\/web.consaguirre.com.ar\/noticias"]}]}},"_links":{"self":[{"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/6909"}],"collection":[{"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=6909"}],"version-history":[{"count":1,"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/6909\/revisions"}],"predecessor-version":[{"id":6911,"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/6909\/revisions\/6911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/media\/6910"}],"wp:attachment":[{"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=6909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=6909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.consaguirre.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=6909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}